{"id":20492,"date":"2020-05-26T15:09:21","date_gmt":"2020-05-26T15:09:21","guid":{"rendered":"https:\/\/www.jacca.com\/%d9%85%d8%b9%d9%84%d9%88%d9%85%d8%a7%d8%aa-%d8%b9%d9%86%d8%a7\/"},"modified":"2023-02-01T13:26:10","modified_gmt":"2023-02-01T13:26:10","slug":"%d9%85%d8%b9%d9%84%d9%88%d9%85%d8%a7%d8%aa-%d8%b9%d9%86%d8%a7","status":"publish","type":"page","link":"https:\/\/www.jacca.com\/ar\/%d9%85%d8%b9%d9%84%d9%88%d9%85%d8%a7%d8%aa-%d8%b9%d9%86%d8%a7\/","title":{"rendered":"\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0639\u0646\u0627"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"20492\" class=\"elementor elementor-20492 elementor-3825\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f1eb38 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"9f1eb38\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-91e7d12 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"91e7d12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-679fedc elementor-section-content-middle scheme_light elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"679fedc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3030660 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"3030660\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3e084c sc_fly_static elementor-widget elementor-widget-image\" data-id=\"e3e084c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/happy_customer.jpg\" class=\"attachment-full size-full wp-image-20242\" alt=\"\" srcset=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/happy_customer.jpg 1920w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/happy_customer-300x169.jpg 300w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/happy_customer-1024x576.jpg 1024w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/happy_customer-768x432.jpg 768w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/happy_customer-1536x864.jpg 1536w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/happy_customer-370x208.jpg 370w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/happy_customer-1290x725.jpg 1290w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/happy_customer-840x473.jpg 840w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/happy_customer-410x231.jpg 410w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/happy_customer-600x338.jpg 600w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/happy_customer-270x152.jpg 270w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff553a0 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"ff553a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9795690 sc_layouts_hide_on_mobile sc_fly_static elementor-widget elementor-widget-image\" data-id=\"9795690\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1252\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/gorsel_9.jpg\" class=\"attachment-full size-full wp-image-20230\" alt=\"\" srcset=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/gorsel_9.jpg 1920w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/gorsel_9-300x196.jpg 300w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/gorsel_9-1024x668.jpg 1024w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/gorsel_9-768x501.jpg 768w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/gorsel_9-1536x1002.jpg 1536w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/gorsel_9-370x241.jpg 370w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/gorsel_9-840x548.jpg 840w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/gorsel_9-410x267.jpg 410w, https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/03\/gorsel_9-600x391.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ab61388 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"ab61388\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0dc557 sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"b0dc557\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_item_subtitle_above sc_item_title_style_default\">\u0645\u0646 \u0646\u062d\u0646 \u0628\u0627\u062e\u062a\u0635\u0627\u0631\u061f<\/span><h1 class=\"sc_item_title sc_title_title sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0639\u0646\u0627<\/span><\/h1><div class=\"sc_item_descr sc_title_descr\"><p>\u0646\u062d\u0646 \u0641\u0631\u064a\u0642 \u064a\u0624\u0645\u0646 \u0628\u0623\u0647\u0645\u064a\u0629 \u0627\u0644\u062a\u0641\u0627\u0639\u0644 \u0628\u064a\u0646 \u0627\u0644\u0639\u0645\u0644\u0627\u0621 \u0648\u0627\u0644\u0634\u0631\u0643\u0627\u062a \u0648\u0627\u0644\u0645\u0648\u0638\u0641\u064a\u0646. \u0645\u0646 \u0623\u062c\u0644 \u062a\u062d\u0633\u064a\u0646 \u0647\u0630\u0647 \u0627\u0644\u062a\u0641\u0627\u0639\u0644\u0627\u062a \u0645\u0639 \u0627\u0644\u062d\u0644\u0648\u0644 \u0627\u0644\u0631\u0642\u0645\u064a\u0629 \u0648\u062a\u0642\u062f\u064a\u0645 \u0627\u0644\u062f\u0639\u0645 \u0627\u0644\u062a\u0634\u063a\u064a\u0644\u064a \u0644\u0644\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u062a\u064a \u0646\u0639\u0645\u0644 \u0645\u0639\u0647\u0627 \u060c \u0623\u0646\u0634\u0623\u0646\u0627 \u0647\u0630\u0647 \u0627\u0644\u0645\u0646\u0635\u0629 \u0648\u0623\u0637\u0644\u0642\u0646\u0627 \u0639\u0644\u064a\u0647\u0627 \u0627\u0633\u0645 \"My Name Badge\". \u0645\u0639 \u0627\u0644\u0627\u0639\u062a\u0642\u0627\u062f \u0628\u0623\u0646\u0646\u0627 \u0628\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u062c\u0639\u0644\u0647 \u0644\u0627 \u064a\u064f\u0646\u0633\u0649 \u0641\u064a \u0627\u0644\u0639\u0627\u0644\u0645 \u0627\u0644\u0639\u0627\u0644\u0645\u064a \u0648\u0639\u0627\u0644\u0645 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a \u060c \u0641\u0642\u062f \u062a\u0637\u0648\u0631 \u0647\u0630\u0627 \u0627\u0644\u0627\u0633\u0645 \u0628\u0645\u0631\u0648\u0631 \u0627\u0644\u0648\u0642\u062a \u0648\u0623\u0635\u0628\u062d \u0639\u0644\u0627\u0645\u062a\u0646\u0627 \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629 \u0627\u0644\u062d\u0627\u0644\u064a\u0629 \u0644\u0645\u0646\u0635\u062a\u0646\u0627 \"Jacca\". \u0628\u0641\u0636\u0644 \u062c\u0647\u0648\u062f\u0646\u0627 \u0627\u0644\u0637\u0648\u064a\u0644\u0629 \u0648\u062d\u0644\u0648\u0644\u0646\u0627 \u0627\u0644\u0645\u0628\u062a\u0643\u0631\u0629 \u060c \u0623\u0635\u0628\u062d\u062a Jacca \u0645\u0646\u0635\u0629 \u0634\u0647\u064a\u0631\u0629 \u0644\u0644\u0641\u0646\u0627\u062f\u0642 \u0648\u0627\u0644\u0645\u0642\u0627\u0647\u064a \u0648\u0627\u0644\u0645\u0637\u0627\u0639\u0645 \u0648\u0627\u0644\u0644\u0627\u0639\u0628\u064a\u0646 \u0627\u0644\u0622\u062e\u0631\u064a\u0646 \u0641\u064a \u0635\u0646\u0627\u0639\u0629 \u0627\u0644\u062e\u062f\u0645\u0627\u062a.<\/p>\n<p>\u0628\u0627\u0644\u0637\u0631\u064a\u0642\u0629 \u0627\u0644\u062a\u064a \u0628\u062f\u0623\u0646\u0627 \u0628\u0647\u0627 \u0643\u0634\u0631\u0643\u0629 \u0628\u0631\u0645\u062c\u064a\u0627\u062a \u0635\u063a\u064a\u0631\u0629 \u060c \u064a\u062a\u0645 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0645\u0646\u0635\u062a\u0646\u0627 \u0628\u0646\u0634\u0627\u0637 \u0641\u064a \u0622\u0644\u0627\u0641 \u0627\u0644\u0645\u0648\u0627\u0642\u0639 \u0627\u0644\u064a\u0648\u0645 \u0648\u0646\u062d\u0646 \u0646\u0634\u0639\u0631 \u0628\u0633\u0639\u0627\u062f\u0629 \u063a\u0627\u0645\u0631\u0629 \u0644\u0623\u0646\u0646\u0627 \u0646\u0633\u062a\u0637\u064a\u0639 \u0623\u0646 \u0646\u062c\u0639\u0644 \u0627\u0644\u062d\u064a\u0627\u0629 \u0623\u0643\u062b\u0631 \u0625\u0645\u062a\u0627\u0639\u064b\u0627 \u0644\u0644\u0634\u0631\u0643\u0627\u062a \u0648\u0627\u0644\u0645\u0648\u0638\u0641\u064a\u0646 \u0648\u0627\u0644\u0639\u0645\u0644\u0627\u0621.<\/p>\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e3c3f5 sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"0e3c3f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><h5 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">\u0634\u0643\u0631\u0627 \u062c\u0632\u064a\u0644\u0627 \u0644\u0643 \u0625\u0630\u0627 \u0642\u0631\u0623\u062a \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0627\u0644. \u0628\u0641\u0636\u0644\u0643\u0645 \u060c \u0646\u062d\u0646 \u0646\u0641\u0647\u0645 \u0628\u0634\u0643\u0644 \u0623\u0641\u0636\u0644 \u0623\u0646\u0646\u0627 \u0646\u0633\u064a\u0631 \u0639\u0644\u0649 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0635\u062d\u064a\u062d.<\/span><\/h5><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5eea42ba elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"5eea42ba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c78c432 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"4c78c432\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca9dcb3 sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"ca9dcb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><h3 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">\u0623\u0639\u0632\u0627\u0626\u064a \u0634\u0631\u0643\u0627\u0621 \u0627\u0644\u0639\u0645\u0644<\/span><\/h3><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b6d4e36 sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"3b6d4e36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28e93c0e elementor-arrows-position-inside sc_fly_static elementor-widget elementor-widget-image-carousel\" data-id=\"28e93c0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\u0639\u0627\u0631\u0636 \u0627\u0644\u0635\u0648\u0631\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/saraymuhallebicisi.png\" alt=\"saraymuhallebicisi\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/sutis.png\" alt=\"sutis\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/mado.png\" alt=\"mado\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/thehunger.png\" alt=\"thehunger\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/doubletree.png\" alt=\"doubletree\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/agaoglu.png\" alt=\"agaoglu\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/mengerler.png\" alt=\"mengerler\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/bigmammas.png\" alt=\"bigmammas\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/atakoytowers.png\" alt=\"atakoytowers\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/liva.png\" alt=\"liva\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/seyran.png\" alt=\"seyran\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/dardenia.png\" alt=\"dardenia\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/ramada.png\" alt=\"ramada\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.jacca.com\/wp-content\/uploads\/2022\/02\/lokma.png\" alt=\"lokma\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0645\u0646 \u0646\u062d\u0646 \u0628\u0627\u062e\u062a\u0635\u0627\u0631\u061f \u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0639\u0646\u0627 \u0646\u062d\u0646 \u0641\u0631\u064a\u0642 \u064a\u0624\u0645\u0646 \u0628\u0623\u0647\u0645\u064a\u0629 \u0627\u0644\u062a\u0641\u0627\u0639\u0644 \u0628\u064a\u0646 \u0627\u0644\u0639\u0645\u0644\u0627\u0621 \u0648\u0627\u0644\u0634\u0631\u0643\u0627\u062a \u0648\u0627\u0644\u0645\u0648\u0638\u0641\u064a\u0646. \u0645\u0646 \u0623\u062c\u0644 \u062a\u062d\u0633\u064a\u0646 \u0647\u0630\u0647 \u0627\u0644\u062a\u0641\u0627\u0639\u0644\u0627\u062a \u0645\u0639 \u0627\u0644\u062d\u0644\u0648\u0644 \u0627\u0644\u0631\u0642\u0645\u064a\u0629 \u0648\u062a\u0642\u062f\u064a\u0645 \u0627\u0644\u062f\u0639\u0645 \u0627\u0644\u062a\u0634\u063a\u064a\u0644\u064a \u0644\u0644\u0634\u0631\u0643\u0627\u062a \u0627\u0644\u062a\u064a \u0646\u0639\u0645\u0644 \u0645\u0639\u0647\u0627 \u060c&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-20492","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.jacca.com\/ar\/wp-json\/wp\/v2\/pages\/20492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jacca.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.jacca.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.jacca.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jacca.com\/ar\/wp-json\/wp\/v2\/comments?post=20492"}],"version-history":[{"count":4,"href":"https:\/\/www.jacca.com\/ar\/wp-json\/wp\/v2\/pages\/20492\/revisions"}],"predecessor-version":[{"id":20579,"href":"https:\/\/www.jacca.com\/ar\/wp-json\/wp\/v2\/pages\/20492\/revisions\/20579"}],"wp:attachment":[{"href":"https:\/\/www.jacca.com\/ar\/wp-json\/wp\/v2\/media?parent=20492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}